{"id":1174,"date":"2017-08-30T12:47:18","date_gmt":"2017-08-30T12:47:18","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?p=1174"},"modified":"2025-12-23T23:41:41","modified_gmt":"2025-12-23T23:41:41","slug":"fractal-estara-participando-en-la-primera-version-de-la-fonda-geek-lv1","status":"publish","type":"post","link":"https:\/\/fractaljuegos.cl\/en\/fractal-estara-participando-en-la-primera-version-de-la-fonda-geek-lv1\/","title":{"rendered":"Fractal estar\u00e1 participando en la primera versi\u00f3n de La Fonda Geek Lv1"},"content":{"rendered":"<div data-breakout=\"normal\">\n<p id=\"viewer-d0ftd\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">El pr\u00f3ximo s\u00e1bado 9 de septiembre, Fractal estar\u00e1 participando en la primera versi\u00f3n de La Fonda Geek Lv1 que se desarrollar\u00e1 en Convoy ubicado en Exposici\u00f3n 1082, en la comuna de Santiago.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block4\"><span style=\"font-size: inherit;\">Dentro de las actividades que se realizar\u00e1n se encuentra el primer torneo oficial de Patchwork, el rodeo de robots del Club Arduino, entre muchas m\u00e1s que podr\u00e1s disfrutar ese d\u00eda. Puedes encontrar m\u00e1s informaci\u00f3n del evento en el siguiente <\/span><a class=\"aL8A4 _9-cXI\" style=\"font-size: inherit;\" href=\"http:\/\/www.facebook.com\/events\/1852247381759292\/?acontext=%7B%22action_history%22%3A%22null%22%7D\" target=\"_blank\" rel=\"noopener\" data-hook=\"web-link\">link.<\/a><\/div>\n<div data-hook=\"rcv-block7\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-fusit\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\"><a class=\"_3KWx2\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/Patchwork\/\" target=\"__blank\">#Patchwork<\/a> <a class=\"_3KWx2\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/Torneo\/\" target=\"__blank\">#Torneo<\/a> <a class=\"_3KWx2\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/Fonda\/\" target=\"__blank\">#Fonda<\/a><\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo s\u00e1bado 9 de septiembre, Fractal estar\u00e1 participando en la primera versi\u00f3n de La Fonda Geek Lv1 que se desarrollar\u00e1 en Convoy ubicado en Exposici\u00f3n 1082, en la comuna de Santiago. Dentro de las actividades que se realizar\u00e1n se encuentra el primer torneo oficial de Patchwork, el rodeo de robots del Club Arduino, entre &#8230; <a title=\"Fractal estar\u00e1 participando en la primera versi\u00f3n de La Fonda Geek Lv1\" class=\"read-more\" href=\"https:\/\/fractaljuegos.cl\/en\/fractal-estara-participando-en-la-primera-version-de-la-fonda-geek-lv1\/\" aria-label=\"Read more about Fractal estar\u00e1 participando en la primera versi\u00f3n de La Fonda Geek Lv1\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":1175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":3,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1174\/revisions"}],"predecessor-version":[{"id":4214,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1174\/revisions\/4214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media\/1175"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/categories?post=1174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tags?post=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}