{"id":1200,"date":"2018-10-09T13:11:07","date_gmt":"2018-10-09T13:11:07","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?p=1200"},"modified":"2025-12-23T23:40:50","modified_gmt":"2025-12-23T23:40:50","slug":"unamos-nuestras-mentes-con-the-mind","status":"publish","type":"post","link":"https:\/\/fractaljuegos.cl\/en\/unamos-nuestras-mentes-con-the-mind\/","title":{"rendered":"\u00a1Unamos nuestras mentes con The Mind!"},"content":{"rendered":"<p>A mediados de Octubre, es decir en las pr\u00f3ximas semanas, llegar\u00e1 a Chile y Mexico el juego The Mind, editado al castellano por Fractal Juegos. Se trata de un t\u00edtulo que carga con una cuota de pol\u00e9mica, ya que muchos fan\u00e1ticos de los juegos de tablero debaten sobre si existe realmente una estrategia para ganarlo; incluso, se cuestionan si es realmente un juego de mesa, o m\u00e1s bien deber\u00edamos catalogarlo como una mera actividad social sin ninguna clase de estrategia.<\/p>\n<p>Dicha discusi\u00f3n se ve ahondada a\u00fan m\u00e1s con la nominaci\u00f3n al Spiel des Jahres que obtuvo The Mind a mediados de a\u00f1o. Aunque no obtuvo el premio -lo gan\u00f3 el hermoso juego Azul, de Michael Kiesling- solo estar nominado permiti\u00f3 que muchas m\u00e1s personas se atrevieran a darle una oportunidad a este concepto revolucionario de apelar a los poderes telep\u00e1ticos de los jugadores.<\/p>\n<div data-breakout=\"normal\">\n<p id=\"viewer-2p0s1\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">Creado por Wolfgang Warsch y publicado originalmente por la editorial alemana <a class=\"aL8A4 _9-cXI\" href=\"http:\/\/www.nsv.de\/\" target=\"_blank\" rel=\"noopener\" data-hook=\"web-link\"><span style=\"color: #61ce70;\"><strong>N\u00fcrnberger Spielkarten Verlag (NSV),<\/strong><\/span><\/a> The Mind es un juego colaborativo compuesto por un mazo de cartas numeradas entre el 1 y el 100, cartas de nivel y dos clases m\u00e1s de cartas especiales. Los jugadores tendr\u00e1n la misi\u00f3n de ir jugando las cartas de su mano en orden ascendente al centro de la mesa en un solo pozo com\u00fan, sin un orden pre establecido de juego. \u00bfCu\u00e1l es la dificultad? Los participantes tienen la gran condici\u00f3n de no poder comunicarse de ning\u00fan modo m\u00e1s que con su mirada. El grupo va completando distintos niveles, donde en el primer nivel tendremos una sola carta en nuestra mano; en el segundo nivel tendremos 2 cartas y as\u00ed sucesivamente. Adem\u00e1s, algunos niveles nos dar\u00e1n recompensas, que pueden ser vidas extras o cartas de estrella ninja, que ser\u00e1n utilizadas en momentos espec\u00edficos para ayudarnos.<\/span><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span style=\"font-size: inherit;\">Puede parecer que la consigna es simple. Pero la verdad es que tener \u00e9xito en esta misi\u00f3n no es para nada sencillo. Deberemos ir conociendo a nuestro grupo cada vez m\u00e1s, logrando sincronizar nuestra sensaci\u00f3n subjetiva del tiempo. Uniendo nuestras mentes para poder lograr completar cada uno de los niveles.<\/span><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span style=\"font-size: inherit;\">Pronto podr\u00e1s encontrar este juego completamente en espa\u00f1ol, en las mejores tiendas, y podr\u00e1s darte cuenta cual es el estado actual de tus habilidades ps\u00edquicas.<\/span><\/p>\n<p dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/92b253_f09a3368176349aea45cd036e7806a30~mv2.jpg\/v1\/fill\/w_350,h_438,al_c,q_80,usm_0.66_1.00_0.01,enc_avif,quality_auto\/92b253_f09a3368176349aea45cd036e7806a30~mv2.jpg\" \/><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A mediados de Octubre, es decir en las pr\u00f3ximas semanas, llegar\u00e1 a Chile y Mexico el juego The Mind, editado al castellano por Fractal Juegos. Se trata de un t\u00edtulo que carga con una cuota de pol\u00e9mica, ya que muchos fan\u00e1ticos de los juegos de tablero debaten sobre si existe realmente una estrategia para ganarlo; &#8230; <a title=\"\u00a1Unamos nuestras mentes con The Mind!\" class=\"read-more\" href=\"https:\/\/fractaljuegos.cl\/en\/unamos-nuestras-mentes-con-the-mind\/\" aria-label=\"Read more about \u00a1Unamos nuestras mentes con The Mind!\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":1201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/comments?post=1200"}],"version-history":[{"count":4,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1200\/revisions"}],"predecessor-version":[{"id":4207,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1200\/revisions\/4207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media\/1201"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/categories?post=1200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tags?post=1200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}