{"id":1208,"date":"2019-01-25T14:28:59","date_gmt":"2019-01-25T14:28:59","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?p=1208"},"modified":"2025-12-23T23:40:30","modified_gmt":"2025-12-23T23:40:30","slug":"estrenamos-canal-de-youtube-e-instagram-tv","status":"publish","type":"post","link":"https:\/\/fractaljuegos.cl\/en\/estrenamos-canal-de-youtube-e-instagram-tv\/","title":{"rendered":"Estrenamos Canal de Youtube e Instagram TV"},"content":{"rendered":"<div data-breakout=\"normal\">\n<p id=\"viewer-62m9s\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">Uno de nuestros grandes desaf\u00edos para este 2019 es fortalecer nuestro area de marketing, y nuestra gran primera acci\u00f3n del a\u00f1o fue abrir nuestro canal de Youtube e Instagram TV. <\/span><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">Ambos canales contar\u00e1n con una gran diversidad de contenidos, desde trailers, unboxing y gameplay de cada uno de nuestros t\u00edtulos.<\/span><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><img decoding=\"async\" draggable=\"false\" src=\"https:\/\/static.wixstatic.com\/media\/5295d1_e192ea898c7f4d5aad89ff3ad9072995~mv2.png\/v1\/fill\/w_740,h_416,al_c,q_85,usm_0.66_1.00_0.01,enc_avif,quality_auto\/5295d1_e192ea898c7f4d5aad89ff3ad9072995~mv2.png\" alt=\"\" data-pin-url=\"https:\/\/fractaljuegos.cl\/post\/2019\/01\/25\/estrenamos-canal-de-youtube-e-instagram-tv\" data-pin-media=\"https:\/\/static.wixstatic.com\/media\/5295d1_e192ea898c7f4d5aad89ff3ad9072995~mv2.png\/v1\/fill\/w_1326,h_746,al_c,q_90\/5295d1_e192ea898c7f4d5aad89ff3ad9072995~mv2.png\" data-ssr-src-done=\"true\" data-load-done=\"\" \/><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span style=\"font-size: inherit;\">Es justamente este \u00faltimo formato en el que m\u00e1s nos enfocaremos, donde contaremos con diferentes influencers y artistas invitados para los diferentes juegos. Nuestro primer gameplay estrenado fue el de Musa, donde contamos con la participaci\u00f3n de Juanjo Nieve, Muy Paola, Chini and the Technicians y Coleccionista de Mil Historias. El video ya lleva m\u00e1s de 10 mil reproducciones en las distintas plataformas.<\/span><\/p>\n<p dir=\"auto\"><span style=\"font-size: inherit;\">El pr\u00f3ximo gameplay se estrenar\u00e1 durante marzo, y se tratar\u00e1 del exitoso juego The Mind.<\/span><\/p>\n<div data-breakout=\"normal\">\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span style=\"font-size: inherit;\">Te invitamos a suscribirte a nuestro canal de <\/span><a class=\"aL8A4 _9-cXI\" style=\"font-size: inherit;\" href=\"http:\/\/www.youtube.com\/channel\/UCibS30A1rWmgv0v9SwTEEyQ?view_as=subscriber\" target=\"_blank\" rel=\"noopener\" data-hook=\"web-link\"><strong><span style=\"color: #6fc6a1;\">Youtube<\/span><\/strong><\/a><span style=\"font-size: inherit;\"> y a seguirnos en <\/span><a class=\"aL8A4 _9-cXI\" style=\"font-size: inherit;\" href=\"http:\/\/www.instagram.com\/fractaljuegos\/\" target=\"_blank\" rel=\"noopener\" data-hook=\"web-link\"><strong><span style=\"color: #6fc6a1;\">Instagram<\/span><\/strong><\/a><span style=\"font-size: inherit;\"> para estar al tanto de todas nuestras novedades.<\/span><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Uno de nuestros grandes desaf\u00edos para este 2019 es fortalecer nuestro area de marketing, y nuestra gran primera acci\u00f3n del a\u00f1o fue abrir nuestro canal de Youtube e Instagram TV. Ambos canales contar\u00e1n con una gran diversidad de contenidos, desde trailers, unboxing y gameplay de cada uno de nuestros t\u00edtulos. Es justamente este \u00faltimo formato &#8230; <a title=\"Estrenamos Canal de Youtube e Instagram TV\" class=\"read-more\" href=\"https:\/\/fractaljuegos.cl\/en\/estrenamos-canal-de-youtube-e-instagram-tv\/\" aria-label=\"Read more about Estrenamos Canal de Youtube e Instagram TV\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":1209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/comments?post=1208"}],"version-history":[{"count":5,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1208\/revisions"}],"predecessor-version":[{"id":4204,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1208\/revisions\/4204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media\/1209"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/categories?post=1208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tags?post=1208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}