{"id":1218,"date":"2019-02-22T14:48:48","date_gmt":"2019-02-22T14:48:48","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?p=1218"},"modified":"2025-12-23T23:40:06","modified_gmt":"2025-12-23T23:40:06","slug":"la-leyenda-del-cerezo","status":"publish","type":"post","link":"https:\/\/fractaljuegos.cl\/en\/la-leyenda-del-cerezo\/","title":{"rendered":"La Leyenda del Cerezo"},"content":{"rendered":"<p>El cerezo es uno de los arboles m\u00e1s emblem\u00e1ticos de la cultura japonesa. Durante la primavera estos arboles florecen por pocos d\u00edas, momento en que la sombra que generan es aprovechada por los ciudadanos para compartir en parques o plazas. La imagen de los p\u00e9talos del cerezo cayendo al suelo es recurrente cuando pensamos en Jap\u00f3n, nos habla sobre la belleza de la naturaleza y lo ef\u00edmero de la existencia. Este juego trata sobre estos arboles y sus misteriosas flores.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/media3.giphy.com\/media\/FWtVYDHIxgGgE\/giphy.gif?cid=dc79c3575c6c4f6356356e5a6b074c43\" \/><\/p>\n<div data-breakout=\"normal\">\n<p id=\"viewer-e282b\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">Una de las primeras novedades de Fractal Juegos para este 2019 ha sido la incorporaci\u00f3n de tres nuevos t\u00edtulos co-editados junto a Iello Games y TCG Factory. Ya hemos escrito anteriormente sobre <strong><span style=\"color: #6fc6a1;\"><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/single-post\/2019\/02\/02\/Raids---Aventuras-de-Vikingos\/\" target=\"_blank\" rel=\"noopener\" data-hook=\"web-link\">Raids<\/a><\/span><\/strong> y <strong><span style=\"color: #6fc6a1;\"><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/single-post\/2019\/02\/09\/Bienvenidos-a-Fairy-Tile\/\" target=\"_blank\" rel=\"noopener\" data-hook=\"web-link\">Fairy Tile<\/a>,<\/span><\/strong> por lo que hoy toca referirnos al \u00faltimo de ellos, cuyo nombre completo es La Leyenda del Cerezo que Florece cada Diez A\u00f1os (y por lo mismo lo llamaremos simplemente \u00abLa Leyenda del Cerezo\u00bb desde ahora en este articulo).<\/span><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span style=\"font-size: inherit;\">La Leyenda del Cerezo es una re implementaci\u00f3n de Hitohira, un juego japon\u00e9s lanzado el 2015, del cual se conservo el arte inspirado en el lejano oriente. Es un juego ligero y din\u00e1mico, donde cada partida dura alrededor de 20 minutos y puede jugarse entre 2 a 4 jugadores. Un elemento central de este juego es el azar y el intento por \u00abcontrolarlo\u00bb. A pesar de que nunca tendremos certeza total sobre las flores que sacaremos de la bolsa, si podemos decidir cuantas flores retirar o incluso los jugadores m\u00e1s expertos podr\u00e1n llevar la cuenta de las flores que han sido retiradas.<\/span><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><img decoding=\"async\" draggable=\"false\" src=\"https:\/\/static.wixstatic.com\/media\/92b253_6c99351e5d3347229977d32ba691fc7a~mv2_d_2113_1690_s_2.png\/v1\/fill\/w_350,h_280,al_c,q_85,usm_0.66_1.00_0.01,enc_avif,quality_auto\/92b253_6c99351e5d3347229977d32ba691fc7a~mv2_d_2113_1690_s_2.png\" alt=\"\" data-pin-url=\"https:\/\/fractaljuegos.cl\/post\/2019\/02\/22\/la-leyenda-del-cerezo\" data-pin-media=\"https:\/\/static.wixstatic.com\/media\/92b253_6c99351e5d3347229977d32ba691fc7a~mv2_d_2113_1690_s_2.png\/v1\/fill\/w_2113,h_1690,al_c,q_95\/92b253_6c99351e5d3347229977d32ba691fc7a~mv2_d_2113_1690_s_2.png\" data-ssr-src-done=\"true\" data-load-done=\"\" \/><\/p>\n<p class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span style=\"font-size: inherit;\">Los principales componentes del juego son 96 fichas de flores de distintos colores (rosadas, amarillas, azules, celestes, blancas y negras siendo est\u00e1s dos \u00faltimas comodines bajo ciertas condiciones) , una bolsa de genero y cuatro pantallas, cuyo rol ser\u00e1 ocultar informaci\u00f3n al resto de los jugadores. Cada partida comienza con la bolsa llena de flores, desde donde cada jugador en su turno intentar\u00e1 retirar un cierto n\u00famero de estas al azar, pero deber\u00e1n cumplirse ciertas condiciones para que el retiro sea exitoso. En el caso de que sea un retiro fallido, el jugador podr\u00e1 quedarse con flores de un solo color a su elecci\u00f3n, en cambio si el retiro se llev\u00f3 adelante con \u00e9xito, podr\u00e1 mantenerlas todas. Adem\u00e1s, luego de un retiro exitoso se deber\u00e1 decidir si dejar las flores delante de la pantalla o detr\u00e1s, quedando ocultos de este modo para el resto de los jugadores.<\/span><\/p>\n<\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-46h0h\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">Adem\u00e1s, y para darle una mayor re jugabilidad al juego, entre los componentes hay 3 cartas de maestr\u00eda, las cuales premian ciertas combinaciones de flores. Cada carta adem\u00e1s trae dos bonificaciones diferentes, una para un nivel b\u00e1sico y el otro avanzado, lo que permite que cada partida sea distinta. <\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block14\"><span style=\"font-size: inherit;\">La forma de obtener puntos de victoria al final de cada partida es distinta para las flores que se posicionan fuera o dentro de la pantalla, Mientras en el primer caso cada jugador ganar\u00e1 puntos por el n\u00famero de flores que recolecte de cada color, en el segundo caso las flores se agrupan entre \u00abcolores c\u00e1lidos\u00bb y \u00abcolores fr\u00edos\u00bb y tendremos que decidir como distribuir nuestras flores-comodines en secreto: ganar\u00e1 m\u00e1s puntos quien tenga m\u00e1s flores de cada tipo.<\/span><\/div>\n<div data-hook=\"rcv-block16\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-ogbv\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">\u00a1Esfu\u00e9rzate por merecer los dones del cerezo legendario en La Leyenda del Cerezo!<\/span><\/p>\n<p><iframe title=\"Trailer La Leyenda del Cerezo que florece cada diez a\u00f1os\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/k97UordqVuk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong><span style=\"color: #6fc6a1;\"><a class=\"_3KWx2\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/IelloGames\/\" target=\"__blank\">#IelloGames<\/a> <a class=\"_3KWx2\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/BoardGame\/\" target=\"__blank\">#BoardGame<\/a> <a class=\"_3KWx2\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/Juegodemesa\/\" target=\"__blank\">#Juegodemesa<\/a> <a class=\"_3KWx2\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/FractalJuegos\/\" target=\"__blank\">#FractalJuegos<\/a> <a class=\"_3KWx2\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/TCGFactory\/\" target=\"__blank\">#TCGFactory<\/a> <a class=\"_3KWx2\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/LaLeyendadelCerezo\/\" target=\"__blank\">#LaLeyendadelCerezo<\/a> <a class=\"_3KWx2\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/blog\/hashtags\/CherryTree\/\" target=\"__blank\">#CherryTree<\/a><\/span><\/strong><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El cerezo es uno de los arboles m\u00e1s emblem\u00e1ticos de la cultura japonesa. Durante la primavera estos arboles florecen por pocos d\u00edas, momento en que la sombra que generan es aprovechada por los ciudadanos para compartir en parques o plazas. La imagen de los p\u00e9talos del cerezo cayendo al suelo es recurrente cuando pensamos en &#8230; <a title=\"La Leyenda del Cerezo\" class=\"read-more\" href=\"https:\/\/fractaljuegos.cl\/en\/la-leyenda-del-cerezo\/\" aria-label=\"Read more about La Leyenda del Cerezo\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":1219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/comments?post=1218"}],"version-history":[{"count":4,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1218\/revisions"}],"predecessor-version":[{"id":4201,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1218\/revisions\/4201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media\/1219"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/categories?post=1218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tags?post=1218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}