{"id":1246,"date":"2020-03-12T03:12:35","date_gmt":"2020-03-12T03:12:35","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?p=1246"},"modified":"2025-12-23T23:38:46","modified_gmt":"2025-12-23T23:38:46","slug":"ha-llegado-saboteur-2","status":"publish","type":"post","link":"https:\/\/fractaljuegos.cl\/en\/ha-llegado-saboteur-2\/","title":{"rendered":"\u00a1Ha llegado Saboteur 2!"},"content":{"rendered":"<div data-breakout=\"normal\">\n<p id=\"viewer-2jrmm\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">\u00a1Hace un par de d\u00edas lleg\u00f3 <a class=\"aL8A4 _9-cXI\" href=\"https:\/\/fractaljuegos.cl\/en\/saboteur2\/\" target=\"_top\" rel=\"noopener\" data-hook=\"web-link\"><strong><span style=\"color: #6fc6a1;\">Saboteur 2<\/span><\/strong><\/a> a las bodegas de Fractal Juegos! Este t\u00edtulo se trata de la expansi\u00f3n del cl\u00e1sico juego de roles ocultos <strong><span style=\"color: #6fc6a1;\"><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/saboteur\/\" target=\"_top\" rel=\"noopener\" data-hook=\"web-link\">Saboteur<\/a> <\/span><\/strong>(para poder jugarlo tendr\u00e1s que tener el juego base Saboteur).<\/span><\/p>\n<div data-breakout=\"normal\">\n<p id=\"viewer-bp81j\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">La historia del juego es que los jugadores somos Enanos Mineros que estamos buscando oro en una mina.. Repentinamente la luz se apaga.. Los Saboteadores han entrado en acci\u00f3n.. Nadie sabe cu\u00e1l es la identidad de los otros jugadores, lo cu\u00e1l deber\u00e1s ir descubriendo a medida que la partida avanza. <\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block5\"><span style=\"font-size: inherit;\">En Saboteur el juego transcurr\u00eda entre Saboteadores contra Mineros. En Saboteur 2 se han incorporado nuevas cartas de Enano, que le dan m\u00e1s profundidad al juego. Entre los enanos, ahora encontramos Mineros Azules y Verdes; dos equipos de Mineros que quieren tener en sus manos el codiciado tesoro&#8230; pero compiten entre ellos. Adem\u00e1s, hay roles especiales como el Jefe, el Perezoso o los Ge\u00f3logos, que tendr\u00e1n condiciones especiales de victoria.<\/span><\/div>\n<div data-hook=\"rcv-block6\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-860o1\" class=\"kWv2d\">\n<div class=\"B43N7 hN6P9\">\n<figure class=\"DIIhI\" data-hook=\"figure-IMAGE\">\n<div class=\"d6VpG\" data-hook=\"image-viewer\">\n<p>&nbsp;<\/p>\n<div id=\"860o1\" class=\"WKoTk EvoAw fZm-X\" data-hook=\"image-viewer-860o1\"><img decoding=\"async\" draggable=\"false\" src=\"https:\/\/static.wixstatic.com\/media\/92b253_2decb5978436480aad75adf7c03303ff~mv2.jpg\/v1\/fill\/w_350,h_222,al_c,q_80,usm_0.66_1.00_0.01,enc_avif,quality_auto\/92b253_2decb5978436480aad75adf7c03303ff~mv2.jpg\" alt=\"\" data-pin-url=\"https:\/\/fractaljuegos.cl\/post\/2020\/03\/12\/-ha-llegado-saboteur-2\" data-pin-media=\"https:\/\/static.wixstatic.com\/media\/92b253_2decb5978436480aad75adf7c03303ff~mv2.jpg\/v1\/fill\/w_900,h_571,al_c,q_85\/92b253_2decb5978436480aad75adf7c03303ff~mv2.jpg\" data-ssr-src-done=\"true\" data-load-done=\"\" \/><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div data-hook=\"rcv-block7\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-1ku63\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">Adem\u00e1s, Saboteur 2 nos trae nuevas cartas de Camino; Puentes, Doble Curva, Cristales o Escaleras har\u00e1n que el laberinto sea m\u00e1s entretenido que nunca. Tambi\u00e9n hay cartas de Camino con Puertas Azules y Verdes; si el camino hacia la carta de Objetivo incluye una carta con una Puerta en ella, los \u00fanicos Mineros que ganar\u00e1n la ronda ser\u00e1n los que coincidan con el color de la Puerta; es decir, dependiendo del color, las Puertas bloquean el camino para los Mineros Azules o Verdes.<\/span><\/p>\n<\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-3i911\" class=\"kWv2d\">\n<div class=\"B43N7 hN6P9\">\n<figure class=\"DIIhI\" data-hook=\"figure-IMAGE\">\n<div class=\"d6VpG\" data-hook=\"image-viewer\">\n<div id=\"3i911\" class=\"WKoTk EvoAw fZm-X\" data-hook=\"image-viewer-3i911\"><img decoding=\"async\" draggable=\"false\" src=\"https:\/\/static.wixstatic.com\/media\/92b253_a670abb1d4074a15a32637adc7a2bb3b~mv2.jpg\/v1\/fill\/w_350,h_233,al_c,q_80,usm_0.66_1.00_0.01,enc_avif,quality_auto\/92b253_a670abb1d4074a15a32637adc7a2bb3b~mv2.jpg\" alt=\"\" data-pin-url=\"https:\/\/fractaljuegos.cl\/post\/2020\/03\/12\/-ha-llegado-saboteur-2\" data-pin-media=\"https:\/\/static.wixstatic.com\/media\/92b253_a670abb1d4074a15a32637adc7a2bb3b~mv2.jpg\/v1\/fill\/w_900,h_600,al_c,q_85\/92b253_a670abb1d4074a15a32637adc7a2bb3b~mv2.jpg\" data-ssr-src-done=\"true\" data-load-done=\"\" \/><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div data-hook=\"rcv-block9\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-8b99j\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">En Saboteur 2, tambi\u00e9n encontraremos nuevas cartas de Acci\u00f3n que nos permitir\u00e1n robarle pepitas de oro a otro jugador, cambiar el rol de los enanos, cambiar manos, entre varias otras. <\/span><\/p>\n<\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-fs7ou\" class=\"kWv2d\">\n<div class=\"B43N7 hN6P9\">\n<figure class=\"DIIhI\" data-hook=\"figure-IMAGE\">\n<div class=\"d6VpG\" data-hook=\"image-viewer\">\n<div id=\"fs7ou\" class=\"WKoTk EvoAw fZm-X\" data-hook=\"image-viewer-fs7ou\"><img decoding=\"async\" draggable=\"false\" src=\"https:\/\/static.wixstatic.com\/media\/92b253_d3a553f4aa044d92befbf8efaa1e138a~mv2.jpg\/v1\/fill\/w_350,h_368,al_c,q_80,usm_0.66_1.00_0.01,enc_avif,quality_auto\/92b253_d3a553f4aa044d92befbf8efaa1e138a~mv2.jpg\" alt=\"\" data-pin-url=\"https:\/\/fractaljuegos.cl\/post\/2020\/03\/12\/-ha-llegado-saboteur-2\" data-pin-media=\"https:\/\/static.wixstatic.com\/media\/92b253_d3a553f4aa044d92befbf8efaa1e138a~mv2.jpg\/v1\/fill\/w_684,h_720,al_c,lg_1,q_85\/92b253_d3a553f4aa044d92befbf8efaa1e138a~mv2.jpg\" data-ssr-src-done=\"true\" data-load-done=\"\" \/><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div data-hook=\"rcv-block11\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-a86db\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">\u00a1Puedes encontrar Saboteur 2 y Saboteur en las <strong><span style=\"color: #6fc6a1;\"><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/tiendas\/\" target=\"_top\" rel=\"noopener\" data-hook=\"web-link\">mejores tiendas del pa\u00eds<\/a><\/span><\/strong>!<\/span><\/p>\n<\/div>\n<\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-cif9n\" class=\"kWv2d\">\n<div class=\"B43N7 hN6P9\">\n<figure class=\"DIIhI\" data-hook=\"figure-IMAGE\">\n<div class=\"d6VpG\" data-hook=\"image-viewer\">\n<div id=\"cif9n\" class=\"WKoTk EvoAw fZm-X\" data-hook=\"image-viewer-cif9n\"><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a1Hace un par de d\u00edas lleg\u00f3 Saboteur 2 a las bodegas de Fractal Juegos! Este t\u00edtulo se trata de la expansi\u00f3n del cl\u00e1sico juego de roles ocultos Saboteur (para poder jugarlo tendr\u00e1s que tener el juego base Saboteur). La historia del juego es que los jugadores somos Enanos Mineros que estamos buscando oro en una &#8230; <a title=\"\u00a1Ha llegado Saboteur 2!\" class=\"read-more\" href=\"https:\/\/fractaljuegos.cl\/en\/ha-llegado-saboteur-2\/\" aria-label=\"Read more about \u00a1Ha llegado Saboteur 2!\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":1247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/comments?post=1246"}],"version-history":[{"count":5,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1246\/revisions"}],"predecessor-version":[{"id":4193,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1246\/revisions\/4193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media\/1247"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/categories?post=1246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tags?post=1246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}