{"id":1363,"date":"2024-06-26T03:43:24","date_gmt":"2024-06-26T03:43:24","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?p=1363"},"modified":"2025-12-23T23:32:52","modified_gmt":"2025-12-23T23:32:52","slug":"conoce-los-nuevos-juegos-que-aterrizan-en-la-familia-fractal","status":"publish","type":"post","link":"https:\/\/fractaljuegos.cl\/en\/conoce-los-nuevos-juegos-que-aterrizan-en-la-familia-fractal\/","title":{"rendered":"Conoce los nuevos juegos que aterrizan en la familia Fractal"},"content":{"rendered":"<p>El invierno no es lo \u00fanico que lleg\u00f3 a Fractal, junto con el clima fr\u00edo, le damos la bienvenida a entretenidos juegos que, estamos seguros, se convertir\u00e1n en sus favoritos de la temporada gracias a su precioso dise\u00f1o y sus din\u00e1micas r\u00e1pidas y entretenidas.<br \/>\n\u00a1Vamos a conocerlos!<\/p>\n<p><span style=\"color: #6fc6a1;\"><a style=\"color: #6fc6a1;\" href=\"https:\/\/boardgamegeek.com\/boardgame\/299169\/spicy\"><strong>Spicy \u00a1El ardiente juego de las mentiras!<\/strong><\/a><\/span><\/p>\n<p>Cuenta la leyenda que muchos a\u00f1os atr\u00e1s, tres grandes felinos decidieron poner fin a su constante disputa por saber qui\u00e9n era el m\u00e1s fuerte. As\u00ed que, en vez de seguir luchando, decidieron a\u00f1adir un toque de emoci\u00f3n a sus vidas con una <span style=\"color: #6fc6a1;\"><a style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/items\/spicy\/\">competencia muy particular<\/a><\/span>\u2026 \u00a1De especias picantes!<br \/>\nEl problema fue que ninguno fue capaz de jugar sin hacer trampas, lo que termin\u00f3 en un interesante \u00a1y muy ardiente! juego de enga\u00f1os.<\/p>\n<p><strong>\u00bfEst\u00e1s listo para jugar?<br \/>\n<\/strong>1. Cada participante coloca una carta boca abajo y anuncia en voz alta su n\u00famero y especie.<br \/>\n2. \u00bfCrees que alguien est\u00e1 mintiendo? \u00a1Desaf\u00eda la especia o el n\u00famero! Supongamos que eliges desafiar el n\u00famero\u2026<br \/>\n3. Si la carta revelada muestra el n\u00famero correcto (aunque la especia sea diferente), pierdes el desaf\u00edo. El participante que jug\u00f3 la carta gana la pila completa.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_03df830e7c4644c7b1255986034c1210~mv2.png\/v1\/fill\/w_304,h_304,fp_0.50_0.50,q_90\/65c498_03df830e7c4644c7b1255986034c1210~mv2.webp\" \/> <img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_0e741045814a45e799f1d89e59bb3627~mv2.png\/v1\/fill\/w_305,h_304,fp_0.50_0.50,q_90\/65c498_0e741045814a45e799f1d89e59bb3627~mv2.webp\" \/> <img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_4759959619bc4839892985632c053cd8~mv2.png\/v1\/fill\/w_304,h_304,fp_0.50_0.50,q_90\/65c498_4759959619bc4839892985632c053cd8~mv2.webp\" \/><\/p>\n<p><strong><span style=\"color: #6fc6a1;\"><a style=\"color: #6fc6a1;\" href=\"https:\/\/boardgamegeek.com\/boardgame\/355735\/hungry-monkey\">Mono Glot\u00f3n \u00a1Transf\u00f3rmate en el rey de esta selva!<\/a><\/span><\/strong><\/p>\n<p>Hace mucho tiempo, un <span style=\"color: #6fc6a1;\"><a style=\"color: #6fc6a1;\" href=\"https:\/\/fractaljuegos.cl\/en\/items\/mono-glot%C3%B3n\/\">Mono Glot\u00f3n<\/a><\/span> perdi\u00f3 su desayuno en la selva. Pero, para su fortuna, los animales de la selva decidieron ayudarlo en su b\u00fasqueda. En este entretenido juego, tienes una mano con cartas de Animal y otras bocabajo en una fila frente tuyo. Para ganar debes ser la primera persona en jugar todas sus cartas, primero las de su mano y luego las de tu fila.<\/p>\n<p><strong>\u00bfEst\u00e1s listo para jugar?<br \/>\n<\/strong>1. Cada participante usa su turno para jugar cartas de Animal en la pila de Animales, en el sentido de las agujas del reloj.<br \/>\n2. Juega una o m\u00e1s cartas bocarriba en la pila de Animales.<br \/>\n3.\u00a0Si consigues cuatro cartas iguales \u00a1Activas un efecto especial! De lo contrario, si puedes activar el efecto de un animal, debes hacerlo.<br \/>\n4. Robar del mazo hasta tener 3 cartas en tu mano (a menos que se haya revelado la carta de Gatito Malo).<\/p>\n<p>\u00a1La primera persona en quedarse sin cartas gana!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_4d21fb2cf83f43dd9a81ed013e6e14fe~mv2.png\/v1\/fill\/w_400,h_400,fp_0.50_0.50,q_90\/65c498_4d21fb2cf83f43dd9a81ed013e6e14fe~mv2.webp\" \/> <img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_b372ad43a32b437fa02e2e308488ae5b~mv2.png\/v1\/fill\/w_400,h_400,fp_0.50_0.50,q_90\/65c498_b372ad43a32b437fa02e2e308488ae5b~mv2.webp\" \/><\/p>\n<p><span style=\"color: #6fc6a1;\"><a style=\"color: #6fc6a1;\" href=\"https:\/\/boardgamegeek.com\/boardgame\/339214\/no-mercy\"><strong>Pelusas \u00a1Sencillo, colorido y muy entretenido!<\/strong><\/a><\/span><\/p>\n<p>Este es un sencillo juego, que te asegura much\u00edsimas risas y diversi\u00f3n. A las pelusas les encanta ir acumul\u00e1ndose, pero cualquier corriente de aire puede hacer que desaparezcan en un momento. Prueba tu suerte sacando pelusas del mont\u00f3n de polvo y robando pelusas al resto para acumular la mayor cantidad al final del juego.<br \/>\n\u00a1Nunca hab\u00eda sido tan divertido recoger pelusas!<\/p>\n<p><strong>\u00bfEst\u00e1s listo para jugar?<br \/>\n<\/strong>1. Recoge pelusas. Si la persona tiene cartas bocarriba delante suyo al principio de su turno, las recoge todas y las deja en un mont\u00f3n bocabajo, formando su mont\u00f3n de puntos para el final de la partida.<br \/>\n2. Luego, debe tomar cartas del mont\u00f3n de polvo y colocarlas bocarriba enfrente suyo. Las cartas del mismo tipo se agrupan por valores, de manera que el resto de los participantes pueda ver cu\u00e1ntas cartas tiene. Despu\u00e9s de revelar cada carta, puede decidir si seguir sacando cartas o plantarse.<br \/>\n3. Cada vez que una persona saca una carta, puede, adem\u00e1s, si quiere, robar todas las cartas del mismo valor que est\u00e9n delante del resto de participantes, a\u00f1adi\u00e9ndolas a sus cartas bocarriba.<\/p>\n<p>Qu\u00e9date con las pelusas y gana.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_191f6210ff6d419aa6cd4fdf55070f26~mv2.png\/v1\/fill\/w_331,h_278,al_c,q_85,usm_0.66_1.00_0.01,enc_avif,quality_auto\/65c498_191f6210ff6d419aa6cd4fdf55070f26~mv2.png\" alt=\"ree\" \/><\/p>\n<p>Encuentra nuestras novedades y los dem\u00e1s juegos de nuestro cat\u00e1logo en los diferentes puntos de venta que tenemos a lo largo de Chile.<\/p>","protected":false},"excerpt":{"rendered":"<p>El invierno no es lo \u00fanico que lleg\u00f3 a Fractal, junto con el clima fr\u00edo, le damos la bienvenida a entretenidos juegos que, estamos seguros, se convertir\u00e1n en sus favoritos de la temporada gracias a su precioso dise\u00f1o y sus din\u00e1micas r\u00e1pidas y entretenidas. \u00a1Vamos a conocerlos! Spicy \u00a1El ardiente juego de las mentiras! Cuenta &#8230; <a title=\"Conoce los nuevos juegos que aterrizan en la familia Fractal\" class=\"read-more\" href=\"https:\/\/fractaljuegos.cl\/en\/conoce-los-nuevos-juegos-que-aterrizan-en-la-familia-fractal\/\" aria-label=\"Read more about Conoce los nuevos juegos que aterrizan en la familia Fractal\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":1364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/comments?post=1363"}],"version-history":[{"count":5,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1363\/revisions"}],"predecessor-version":[{"id":4159,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1363\/revisions\/4159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media\/1364"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/categories?post=1363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tags?post=1363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}