{"id":1369,"date":"2024-07-18T03:44:24","date_gmt":"2024-07-18T03:44:24","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?p=1369"},"modified":"2025-12-23T23:32:35","modified_gmt":"2025-12-23T23:32:35","slug":"tras-los-pasos-de-darwin-llega-a-fractal-juegos","status":"publish","type":"post","link":"https:\/\/fractaljuegos.cl\/en\/tras-los-pasos-de-darwin-llega-a-fractal-juegos\/","title":{"rendered":"\u00abTras los pasos de Darwin\u00bb llega a Fractal Juegos"},"content":{"rendered":"<div data-breakout=\"normal\">\n<p id=\"viewer-cau8k5011\" class=\"-kA22 pbpjT jmBhI t8vt2\" dir=\"auto\"><span class=\"k6Gbk jmBhI\">Este domingo 21 de julio se celebran los premios Oscar del mundo de los juegos de mesa y al fin sabremos los ganadores de los <strong><span style=\"color: #6fc6a1;\"><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/www.spiel-des-jahres.de\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-hook=\"web-link\"><u>Spiel des Jahres 2024<\/u><\/a><\/span><\/strong>. Y esta edici\u00f3n es particularmente especial para nosotros, ya que uno de los nominados a juego del a\u00f1o aterriza al cat\u00e1logo de Fractal a fines de a\u00f1o: <a class=\"aL8A4 _9-cXI\" href=\"https:\/\/boardgamegeek.com\/boardgame\/376683\/in-the-footsteps-of-darwin\" target=\"_blank\" rel=\"noopener noreferrer\" data-hook=\"web-link\"><u><strong><span style=\"color: #6fc6a1;\">Tras los pasos de Darwin<\/span><\/strong><\/u><\/a>, de la editorial francesa <span style=\"color: #6fc6a1;\"><strong><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/sorryweare.fr\/en\/game\/in-the-footsteps-of-darwin\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-hook=\"web-link\"><u>Sorry we are French<\/u><\/a>.<\/strong><\/span><\/span><\/p>\n<\/div>\n<p><span style=\"font-size: inherit;\">Su precioso dise\u00f1o, interesante tem\u00e1tica y su din\u00e1mica desafiante lo ha hecho merecedor de esta importante nominaci\u00f3n, adem\u00e1s de ser finalista del <\/span><span style=\"color: #6fc6a1;\"><strong><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/boardgamegeek.com\/boardgamehonor\/102008\/2024-as-dor-jeu-de-lannee-nominee\" target=\"_blank\" rel=\"noopener noreferrer\" data-hook=\"web-link\"><u>As D\u00b4Or 2024<\/u><\/a><\/strong><\/span><span style=\"font-size: inherit;\"> y ser parte de los ganadores del <\/span><strong style=\"font-size: inherit;\"><span style=\"color: #6fc6a1;\"><a class=\"aL8A4 _9-cXI\" style=\"color: #6fc6a1;\" href=\"https:\/\/www.mensamindgames.com\/about\/winning-games\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-hook=\"web-link\"><u>Mensa Select Games<\/u><\/a>.<\/span><\/strong><\/p>\n<div data-breakout=\"normal\">\n<p><span style=\"font-size: inherit;\">En este hermoso juego, podr\u00e1s ayudar a, nada m\u00e1s ni nada menos que, Charles Darwin para que pueda terminar de escribir El Origen de las Especies. Veinte a\u00f1os despu\u00e9s de su expedici\u00f3n alrededor del mundo, Darwin necesita recolectar nueva informaci\u00f3n de la vida animal, especialmente en los continentes donde apenas pudo poner un pie, como Norteam\u00e9rica, Asia y parte de \u00c1frica.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block6\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-ipixr1917\" class=\"-kA22 pbpjT jmBhI t8vt2\" dir=\"auto\"><span class=\"k6Gbk jmBhI\">\u00a0<\/span><span style=\"font-size: inherit;\">\u00abAdem\u00e1s de ser sumamente entretenido, es un juego que incluye mucho contenido educativo sobre el estudio de las diferentes especies que sirvieron de sustento para El Origen de las Especies. El juego, adem\u00e1s de venir con un reglamento, trae un ap\u00e9ndice donde se relata el viaje completo de Darwin en el Beagle, y todas las especies estudiadas en los diferentes pa\u00edses donde desembarc\u00f3. En mi opini\u00f3n, es un juego perfecto para cualquier ludoteca\/biblioteca, donde adem\u00e1s destaca el acabado est\u00e9tico y material. Perfecto para cautivar a ese publico que a\u00fan no se atreve a incursionar en el mundo de los juegos de mesa modernos\u00bb, nos dice Jos\u00e9 Manuel \u00c1lvarez, co-fundador de Fractal Juegos.<\/span><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div data-hook=\"rcv-block8\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-tqm9c266\" class=\"kWv2d\">\n<div class=\"B43N7\">\n<figure class=\"DIIhI\" data-hook=\"figure-IMAGE\">\n<div class=\"d6VpG\" data-hook=\"image-viewer\">\n<div id=\"tqm9c266\" class=\"WKoTk EvoAw fZm-X\" data-hook=\"image-viewer-tqm9c266\"><img decoding=\"async\" draggable=\"false\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_b598e8a9aa1e458eb851e5fb3b2a4a98~mv2.png\/v1\/fill\/w_627,h_328,al_c,q_85,usm_0.66_1.00_0.01,enc_avif,quality_auto\/65c498_b598e8a9aa1e458eb851e5fb3b2a4a98~mv2.png\" alt=\"ree\" data-pin-url=\"https:\/\/fractaljuegos.cl\/post\/tras-los-pasos-de-darwin-llega-a-fractal-juegos\" data-pin-media=\"https:\/\/static.wixstatic.com\/media\/65c498_b598e8a9aa1e458eb851e5fb3b2a4a98~mv2.png\/v1\/fill\/w_1200,h_627,al_c,q_90\/65c498_b598e8a9aa1e458eb851e5fb3b2a4a98~mv2.png\" data-ssr-src-done=\"true\" data-load-done=\"\" \/><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div data-hook=\"rcv-block9\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-7iq147743\" class=\"-kA22 pbpjT jmBhI t8vt2\" dir=\"auto\"><span class=\"k6Gbk jmBhI\">\u00a0<\/span><\/div>\n<\/div>\n<div data-hook=\"rcv-block10\"><\/div>\n<div data-breakout=\"normal\">\n<p id=\"viewer-vb637432\" class=\"-kA22 pbpjT jmBhI t8vt2\" dir=\"auto\"><span class=\"k6Gbk jmBhI\">Cada participante es un joven naturalista que acaba de subirse a bordo del Beagle para ayudar a Charles Darwin a terminar su libro El Origen de las Especies. Durante este viaje deben estudiar animales, realizar estudios de cartograf\u00eda, publicar descubrimientos y desarrollar teor\u00edas. El objetivo es obtener m\u00e1s Puntos de Victoria (PV) que los dem\u00e1s para determinar qui\u00e9n contribuir\u00e1 m\u00e1s en El Origen de las Especies. Este entretenido y desafiante juego termina cuando cada naturalista ha colocado exactamente 12 losetas en su cuaderno.<\/span><\/p>\n<\/div>\n<div data-hook=\"rcv-block12\"><span style=\"font-size: inherit;\">As\u00ed que prep\u00e1rense para vivir una hermosa aventura este verano, ya que <\/span><a class=\"aL8A4 _9-cXI\" style=\"font-size: inherit;\" href=\"https:\/\/fractaljuegos.cl\/en\/items\/tras-los-pasos-de-darwin\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-hook=\"web-link\"><u><strong><span style=\"color: #6fc6a1;\">Tras los pasos de Darwin<\/span><\/strong><\/u><\/a><span style=\"font-size: inherit;\"> estar\u00e1 llegando a tiendas en diciembre 2024.<\/span><\/div>\n<div data-breakout=\"normal\">\n<div dir=\"auto\"><\/div>\n<div id=\"viewer-3jsk33865\" class=\"-kA22 pbpjT jmBhI t8vt2\" dir=\"auto\"><span style=\"font-size: inherit;\">\u00a1No podemos esperar!<\/span><\/div>\n<\/div>\n<div data-hook=\"rcv-block15\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-2hkfa1827\" class=\"-kA22 pbpjT jmBhI t8vt2\" dir=\"auto\"><span class=\"k6Gbk jmBhI\">\u00a0<\/span><\/div>\n<\/div>\n<div data-hook=\"rcv-block16\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-96snr2075\" class=\"-kA22 pbpjT YY-zb _3DWex\" dir=\"auto\"><span class=\"k6Gbk\">\u00a0<\/span><\/div>\n<\/div>\n<div data-hook=\"rcv-block17\"><\/div>\n<div data-breakout=\"normal\">\n<div id=\"viewer-twny22074\" class=\"kWv2d\">\n<div class=\"B43N7 uY2tw\">\n<figure class=\"DIIhI\" data-hook=\"figure-IMAGE\">\n<div class=\"d6VpG\" data-hook=\"image-viewer\">\n<div id=\"twny22074\" class=\"WKoTk EvoAw fZm-X\" data-hook=\"image-viewer-twny22074\"><img decoding=\"async\" draggable=\"false\" src=\"https:\/\/static.wixstatic.com\/media\/65c498_844eb82a51fe4f4b859cf1e231141e1d~mv2.png\/v1\/fill\/w_740,h_387,al_c,q_85,usm_0.66_1.00_0.01,enc_avif,quality_auto\/65c498_844eb82a51fe4f4b859cf1e231141e1d~mv2.png\" alt=\"ree\" data-pin-url=\"https:\/\/fractaljuegos.cl\/post\/tras-los-pasos-de-darwin-llega-a-fractal-juegos\" data-pin-media=\"https:\/\/static.wixstatic.com\/media\/65c498_844eb82a51fe4f4b859cf1e231141e1d~mv2.png\/v1\/fill\/w_1200,h_627,al_c,q_90\/65c498_844eb82a51fe4f4b859cf1e231141e1d~mv2.png\" data-ssr-src-done=\"true\" data-load-done=\"\" \/><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Este domingo 21 de julio se celebran los premios Oscar del mundo de los juegos de mesa y al fin sabremos los ganadores de los Spiel des Jahres 2024. Y esta edici\u00f3n es particularmente especial para nosotros, ya que uno de los nominados a juego del a\u00f1o aterriza al cat\u00e1logo de Fractal a fines de &#8230; <a title=\"\u00abTras los pasos de Darwin\u00bb llega a Fractal Juegos\" class=\"read-more\" href=\"https:\/\/fractaljuegos.cl\/en\/tras-los-pasos-de-darwin-llega-a-fractal-juegos\/\" aria-label=\"Read more about \u00abTras los pasos de Darwin\u00bb llega a Fractal Juegos\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":1370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/comments?post=1369"}],"version-history":[{"count":9,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1369\/revisions"}],"predecessor-version":[{"id":4157,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/posts\/1369\/revisions\/4157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media\/1370"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/categories?post=1369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tags?post=1369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}