{"id":1841,"date":"2025-11-09T16:06:43","date_gmt":"2025-11-09T16:06:43","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?post_type=punto_de_venta&#038;p=1841"},"modified":"2026-01-23T03:58:03","modified_gmt":"2026-01-23T03:58:03","slug":"de-juegos-cafe","status":"publish","type":"punto_de_venta","link":"https:\/\/fractaljuegos.cl\/en\/punto_de_venta\/de-juegos-cafe\/","title":{"rendered":"De Juegos Caf\u00e9"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"otro_pais":[],"region":[137,78],"tinda_fisica_u_online":[66],"tipo_de_envio":[],"class_list":["post-1841","punto_de_venta","type-punto_de_venta","status-publish","hentry","region-quellon","region-region-de-los-lagos","tinda_fisica_u_online-tienda-fisica"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/1841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/punto_de_venta"}],"version-history":[{"count":1,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/1841\/revisions"}],"predecessor-version":[{"id":1842,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/1841\/revisions\/1842"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1841"}],"wp:term":[{"taxonomy":"otro_pais","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/otro_pais?post=1841"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/region?post=1841"},{"taxonomy":"tinda_fisica_u_online","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tinda_fisica_u_online?post=1841"},{"taxonomy":"tipo_de_envio","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tipo_de_envio?post=1841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}