{"id":1857,"date":"2025-11-09T16:15:25","date_gmt":"2025-11-09T16:15:25","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?post_type=punto_de_venta&#038;p=1857"},"modified":"2026-01-23T04:00:54","modified_gmt":"2026-01-23T04:00:54","slug":"weplay-store-19","status":"publish","type":"punto_de_venta","link":"https:\/\/fractaljuegos.cl\/en\/punto_de_venta\/weplay-store-19\/","title":{"rendered":"Weplay Store"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"otro_pais":[],"region":[133,86],"tinda_fisica_u_online":[66],"tipo_de_envio":[],"class_list":["post-1857","punto_de_venta","type-punto_de_venta","status-publish","hentry","region-rancagua","region-region-de-ohiggins","tinda_fisica_u_online-tienda-fisica"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/1857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/punto_de_venta"}],"version-history":[{"count":1,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/1857\/revisions"}],"predecessor-version":[{"id":1858,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/1857\/revisions\/1858"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=1857"}],"wp:term":[{"taxonomy":"otro_pais","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/otro_pais?post=1857"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/region?post=1857"},{"taxonomy":"tinda_fisica_u_online","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tinda_fisica_u_online?post=1857"},{"taxonomy":"tipo_de_envio","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tipo_de_envio?post=1857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}