{"id":2109,"date":"2025-11-10T14:23:06","date_gmt":"2025-11-10T14:23:06","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?post_type=punto_de_venta&#038;p=2109"},"modified":"2025-11-10T14:23:06","modified_gmt":"2025-11-10T14:23:06","slug":"cone-store-2","status":"publish","type":"punto_de_venta","link":"https:\/\/fractaljuegos.cl\/en\/punto_de_venta\/cone-store-2\/","title":{"rendered":"Cone Store"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"otro_pais":[],"region":[],"tinda_fisica_u_online":[67],"tipo_de_envio":[],"class_list":["post-2109","punto_de_venta","type-punto_de_venta","status-publish","hentry","tinda_fisica_u_online-tienda-online"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/punto_de_venta"}],"version-history":[{"count":1,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2109\/revisions"}],"predecessor-version":[{"id":2110,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2109\/revisions\/2110"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=2109"}],"wp:term":[{"taxonomy":"otro_pais","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/otro_pais?post=2109"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/region?post=2109"},{"taxonomy":"tinda_fisica_u_online","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tinda_fisica_u_online?post=2109"},{"taxonomy":"tipo_de_envio","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tipo_de_envio?post=2109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}