{"id":2186,"date":"2025-11-10T15:10:18","date_gmt":"2025-11-10T15:10:18","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?post_type=punto_de_venta&#038;p=2186"},"modified":"2025-11-10T15:10:18","modified_gmt":"2025-11-10T15:10:18","slug":"juegos-del-bosque","status":"publish","type":"punto_de_venta","link":"https:\/\/fractaljuegos.cl\/en\/punto_de_venta\/juegos-del-bosque\/","title":{"rendered":"Juegos del Bosque"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"otro_pais":[],"region":[],"tinda_fisica_u_online":[67],"tipo_de_envio":[],"class_list":["post-2186","punto_de_venta","type-punto_de_venta","status-publish","hentry","tinda_fisica_u_online-tienda-online"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/punto_de_venta"}],"version-history":[{"count":1,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2186\/revisions"}],"predecessor-version":[{"id":2187,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2186\/revisions\/2187"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=2186"}],"wp:term":[{"taxonomy":"otro_pais","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/otro_pais?post=2186"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/region?post=2186"},{"taxonomy":"tinda_fisica_u_online","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tinda_fisica_u_online?post=2186"},{"taxonomy":"tipo_de_envio","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tipo_de_envio?post=2186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}