{"id":2425,"date":"2025-11-18T19:12:19","date_gmt":"2025-11-18T19:12:19","guid":{"rendered":"https:\/\/fractaljuegos.cl\/?post_type=punto_de_venta&#038;p=2425"},"modified":"2025-11-18T19:12:19","modified_gmt":"2025-11-18T19:12:19","slug":"montevideo-gaming-house","status":"publish","type":"punto_de_venta","link":"https:\/\/fractaljuegos.cl\/en\/punto_de_venta\/montevideo-gaming-house\/","title":{"rendered":"Montevideo Gaming House"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"otro_pais":[72],"region":[],"tinda_fisica_u_online":[],"tipo_de_envio":[74],"class_list":["post-2425","punto_de_venta","type-punto_de_venta","status-publish","hentry","otro_pais-uruguay","tipo_de_envio-envio-internacional"],"acf":[],"_links":{"self":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta"}],"about":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/types\/punto_de_venta"}],"version-history":[{"count":1,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2425\/revisions"}],"predecessor-version":[{"id":2426,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/punto_de_venta\/2425\/revisions\/2426"}],"wp:attachment":[{"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/media?parent=2425"}],"wp:term":[{"taxonomy":"otro_pais","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/otro_pais?post=2425"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/region?post=2425"},{"taxonomy":"tinda_fisica_u_online","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tinda_fisica_u_online?post=2425"},{"taxonomy":"tipo_de_envio","embeddable":true,"href":"https:\/\/fractaljuegos.cl\/en\/wp-json\/wp\/v2\/tipo_de_envio?post=2425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}